{"id":24860,"date":"2024-02-04T14:12:22","date_gmt":"2024-02-04T11:12:22","guid":{"rendered":"https:\/\/thesecretshape.thesecretshape.com\/contacts\/"},"modified":"2024-02-28T11:59:40","modified_gmt":"2024-02-28T08:59:40","slug":"contacts","status":"publish","type":"page","link":"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/","title":{"rendered":"\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u044b"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  responsive_js_composer_custom_css_1193468899\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u0410\u0434\u0440\u0435\u0441:<br \/>\n<span style=\"color: #000000;\"><strong>\u0422\u0430\u0448\u043a\u0435\u043d\u0442, \u0443\u043b\u0438\u0446\u0430 \u0423\u043a\u0447\u0438, 5<br \/>\n(\u0428\u0430\u0439\u0445\u0430\u043d\u0442\u0430\u0445\u0443\u0440\u0441\u043a\u0438\u0439 \u0440\u0430\u0439\u043e\u043d)<\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  responsive_js_composer_custom_css_1893854039\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u0422\u0435\u043b\u0435\u0444\u043e\u043d:<br \/>\n<span style=\"color: #000000;\"><strong>+998 95 709 27 29<\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  responsive_js_composer_custom_css_1270857025\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u042d\u043b. \u043f\u043e\u0447\u0442\u0430:<br \/>\n<span style=\"color: #000000;\"><strong>info@thesecretshape.thesecretshape.com<\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space  responsive_js_composer_custom_css_1681066769\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_row-o-content-middle vc_row-flex responsive_js_composer_custom_css_1370019291\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  responsive_js_composer_custom_css_1446755494\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><iframe loading=\"lazy\" src=\"https:\/\/yandex.ru\/map-widget\/v1\/?um=constructor%3A987e0e772d43da852d9563fe0d0ab991e69edb54bbf7eebbcbf6ab81165551f4&amp;source=constructor\" width=\"100%\" height=\"400\" frameborder=\"0\"><\/iframe><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space  responsive_js_composer_custom_css_766754893\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\r\n\t<div class=\"wpb_single_image wpb_content_element vc_align_left  responsive_js_composer_custom_css_1286007563\">\r\n\t\t\r\n\t\t<figure class=\"wpb_wrapper vc_figure\">\r\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1500\" src=\"https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag1.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"tssmag1\" srcset=\"https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag1.jpg 1000w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag1-200x300.jpg 200w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag1-683x1024.jpg 683w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag1-768x1152.jpg 768w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag1-570x855.jpg 570w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\r\n\t\t<\/figure>\r\n\t<\/div>\r\n<div class=\"vc_empty_space  responsive_js_composer_custom_css_356977462\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\r\n\t<div class=\"wpb_single_image wpb_content_element vc_align_left  responsive_js_composer_custom_css_1600814303\">\r\n\t\t\r\n\t\t<figure class=\"wpb_wrapper vc_figure\">\r\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1500\" src=\"https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag2.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"tssmag2\" srcset=\"https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag2.jpg 1000w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag2-200x300.jpg 200w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag2-683x1024.jpg 683w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag2-768x1152.jpg 768w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag2-570x855.jpg 570w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\r\n\t\t<\/figure>\r\n\t<\/div>\r\n<div class=\"vc_empty_space  responsive_js_composer_custom_css_2106714592\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\r\n\t<div class=\"wpb_single_image wpb_content_element vc_align_left  responsive_js_composer_custom_css_671126987\">\r\n\t\t\r\n\t\t<figure class=\"wpb_wrapper vc_figure\">\r\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1500\" src=\"https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag3.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"tssmag3\" srcset=\"https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag3.jpg 1000w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag3-200x300.jpg 200w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag3-683x1024.jpg 683w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag3-768x1152.jpg 768w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag3-570x855.jpg 570w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\r\n\t\t<\/figure>\r\n\t<\/div>\r\n<div class=\"vc_empty_space  responsive_js_composer_custom_css_1387190469\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\r\n\t<div class=\"wpb_single_image wpb_content_element vc_align_left  responsive_js_composer_custom_css_1797886538\">\r\n\t\t\r\n\t\t<figure class=\"wpb_wrapper vc_figure\">\r\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1500\" src=\"https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag4.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"tssmag4\" srcset=\"https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag4.jpg 1000w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag4-200x300.jpg 200w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag4-683x1024.jpg 683w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag4-768x1152.jpg 768w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag4-570x855.jpg 570w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\r\n\t\t<\/figure>\r\n\t<\/div>\r\n<div class=\"vc_empty_space  responsive_js_composer_custom_css_1223048470\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\r\n\t<div class=\"wpb_single_image wpb_content_element vc_align_left  responsive_js_composer_custom_css_807900899\">\r\n\t\t\r\n\t\t<figure class=\"wpb_wrapper vc_figure\">\r\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1500\" src=\"https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag5.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"tssmag5\" srcset=\"https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag5.jpg 1000w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag5-200x300.jpg 200w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag5-683x1024.jpg 683w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag5-768x1152.jpg 768w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag5-570x855.jpg 570w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\r\n\t\t<\/figure>\r\n\t<\/div>\r\n<div class=\"vc_empty_space  responsive_js_composer_custom_css_2009300244\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\r\n\t<div class=\"wpb_single_image wpb_content_element vc_align_left  responsive_js_composer_custom_css_1848963101\">\r\n\t\t\r\n\t\t<figure class=\"wpb_wrapper vc_figure\">\r\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1500\" src=\"https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag6.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"tssmag6\" srcset=\"https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag6.jpg 1000w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag6-200x300.jpg 200w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag6-683x1024.jpg 683w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag6-768x1152.jpg 768w, https:\/\/thesecretshape.thesecretshape.com\/wp-content\/uploads\/2024\/02\/tssmag6-570x855.jpg 570w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\r\n\t\t<\/figure>\r\n\t<\/div>\r\n<\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"\u0410\u0434\u0440\u0435\u0441: \u0422\u0430\u0448\u043a\u0435\u043d\u0442, \u0443\u043b\u0438\u0446\u0430 \u0423\u043a\u0447\u0438, 5 (\u0428\u0430\u0439\u0445\u0430\u043d\u0442\u0430\u0445\u0443\u0440\u0441\u043a\u0438\u0439 \u0440\u0430\u0439\u043e\u043d) \u0422\u0435\u043b\u0435\u0444\u043e\u043d: +998 95 709 27 29 \u042d\u043b. \u043f\u043e\u0447\u0442\u0430: info@thesecretshape.thesecretshape.com","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-24860","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u044b - Thesecretshape<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/\" \/>\n<meta property=\"og:locale\" content=\"uz_UZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u044b - Thesecretshape\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/\" \/>\n<meta property=\"og:site_name\" content=\"Thesecretshape\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T08:59:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 daqiqa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/\",\"url\":\"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/\",\"name\":\"\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u044b - Thesecretshape\",\"isPartOf\":{\"@id\":\"https:\/\/thesecretshape.thesecretshape.com\/uz\/#website\"},\"datePublished\":\"2024-02-04T11:12:22+00:00\",\"dateModified\":\"2024-02-28T08:59:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/#breadcrumb\"},\"inLanguage\":\"uz-UZ\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\/\/thesecretshape.thesecretshape.com\/?page_id=25340\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u044b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thesecretshape.thesecretshape.com\/uz\/#website\",\"url\":\"https:\/\/thesecretshape.thesecretshape.com\/uz\/\",\"name\":\"Thesecretshape\",\"description\":\"\u0415\u0449\u0451 \u043e\u0434\u0438\u043d \u0441\u0430\u0439\u0442 \u043d\u0430 WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/thesecretshape.thesecretshape.com\/uz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"uz-UZ\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u044b - Thesecretshape","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/","og_locale":"uz_UZ","og_type":"article","og_title":"\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u044b - Thesecretshape","og_url":"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/","og_site_name":"Thesecretshape","article_modified_time":"2024-02-28T08:59:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 daqiqa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/","url":"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/","name":"\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u044b - Thesecretshape","isPartOf":{"@id":"https:\/\/thesecretshape.thesecretshape.com\/uz\/#website"},"datePublished":"2024-02-04T11:12:22+00:00","dateModified":"2024-02-28T08:59:40+00:00","breadcrumb":{"@id":"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/#breadcrumb"},"inLanguage":"uz-UZ","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thesecretshape.thesecretshape.com\/uz\/contacts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/thesecretshape.thesecretshape.com\/?page_id=25340"},{"@type":"ListItem","position":2,"name":"\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u044b"}]},{"@type":"WebSite","@id":"https:\/\/thesecretshape.thesecretshape.com\/uz\/#website","url":"https:\/\/thesecretshape.thesecretshape.com\/uz\/","name":"Thesecretshape","description":"\u0415\u0449\u0451 \u043e\u0434\u0438\u043d \u0441\u0430\u0439\u0442 \u043d\u0430 WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thesecretshape.thesecretshape.com\/uz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"uz-UZ"}]}},"_links":{"self":[{"href":"https:\/\/thesecretshape.thesecretshape.com\/uz\/wp-json\/wp\/v2\/pages\/24860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thesecretshape.thesecretshape.com\/uz\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thesecretshape.thesecretshape.com\/uz\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thesecretshape.thesecretshape.com\/uz\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thesecretshape.thesecretshape.com\/uz\/wp-json\/wp\/v2\/comments?post=24860"}],"version-history":[{"count":16,"href":"https:\/\/thesecretshape.thesecretshape.com\/uz\/wp-json\/wp\/v2\/pages\/24860\/revisions"}],"predecessor-version":[{"id":24921,"href":"https:\/\/thesecretshape.thesecretshape.com\/uz\/wp-json\/wp\/v2\/pages\/24860\/revisions\/24921"}],"wp:attachment":[{"href":"https:\/\/thesecretshape.thesecretshape.com\/uz\/wp-json\/wp\/v2\/media?parent=24860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}